{"id":14446,"date":"2020-08-21T08:45:42","date_gmt":"2020-08-21T08:45:42","guid":{"rendered":"https:\/\/www.aprioripr.com\/?page_id=14446"},"modified":"2023-07-19T10:43:39","modified_gmt":"2023-07-19T10:43:39","slug":"internationale-pr-und-marketingagentur","status":"publish","type":"page","link":"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/","title":{"rendered":"\u00dcber Uns"},"content":{"rendered":"<div  data-label=\"About\" data-id=\"about--1\" data-export-id=\"about-1\" data-category=\"about\" class=\"about-1 content-section\" id=\"about-1\" style=\"background-color: rgb(255, 255, 255); background-image: none;\"><div  class=\"gridContainer\"> <div  class=\"row text-center\"><div  class=\"section-title-col\" data-type=\"column\">   <p  class=\"lead\" style=\"text-align: left;\"><span  style=\"font-weight: 700; color: rgb(0, 0, 0);\">International und Multikulturell.\n<\/span><br ><span  style=\"color: rgb(0, 0, 0);\">Wir sind international t\u00e4tig und ein multikulturelles Team, das weltweit Unternehmen und Startups kreativ und performance-orientiert multilingual unterst\u00fctzt.<\/span><br ><span  style=\"color: rgb(0, 0, 0);\">\nUnsere PR- und Marketingexperten beraten Kunden u.a. in Australien, USA, in den Vereinigten Arabischen Emiraten, Italien, Polen, England, Frankreich, Deutschland, \u00d6sterreich und der Schweiz.\n<\/span><br ><span  style=\"color: rgb(0, 0, 0);\">\nDas apriori Team verf\u00fcgt \u00fcber fundierte Kenntnisse in der Leadgenerierung, Performance Marketing, Public Relations\/Public Affairs, Image-PR, Corporate Communications, Consumer- und Lifestyle-PR, Social Media und <span  style=\"font-weight: 400;\">Influencer Marketing sowie Krisenkommunikation.\n\n<\/span>Wir wuppen Projekte f\u00fcr unsere Kunden mit Begeisterung, Elan und Tatkraft. \n<br ><br >Wir denken und gestalten ganz neue Wege.\nMit unseren kreativen Kommunikationskonzepten begleiten wir Marken langfristig und steigern die Conversion Rate nachhaltig.\n\n<br ><br >Wir decken Kundenbedarfe durch Customer Development auf, testen Mikrobed\u00fcrfnisse und geben Ihnen f\u00fcr Ihre Stakeholder die Grundlage f\u00fcr digitale Erfolgsstories.<\/span><\/p><\/div> <\/div> <div  class=\"row\"> <div  class=\"button-holder space-bottom space-bottom-small\" data-type=\"column\"> <\/div> <div  class=\"col-xs bottom-xs flexbox image-group-bottom-3-img space-bottom-xs center-xs\"> <img  data-size=\"500x300\" alt=\"\" title=\"cropped-103998623_s.jpg\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-103998623_s.jpg\" class=\"left-img shadow-large-black lazyloaded\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-103998623_s.jpg\"> <img  data-size=\"500x300\" alt=\"\" title=\"cropped-20230621_175739-scaled-1.jpg\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-99076392_s.jpg\" class=\"center-img shadow-large-black lazyloaded\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-20230621_175739-scaled-1.jpg\"> <img  data-size=\"500x300\" alt=\"\" title=\"cropped-53124300_s.jpg\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-53124300_s.jpg\" class=\"right-img shadow-large-black lazyloaded\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-53124300_s.jpg\"><\/div> <\/div><\/div> <\/div><div  data-label=\"Gallery\" data-id=\"gallery--1\" data-export-id=\"gallery-1\" data-category=\"gallery\" class=\"gallery-1 content-section content-section-spacing content-relative\" id=\"gallery-1\" style=\"background-color: rgb(255, 255, 255);\"><div  class=\"section-separator-top\">\n    <svg  xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\" data-separator-name=\"triangle\" class=\"section-separator-top\">\n\t<path  class=\"svg-white-bg\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"><\/path>\n<\/svg>\n<\/div><div  class=\"gridContainer\"> <div  class=\"row\"><div  class=\"section-title-col\" data-type=\"column\"> <h2  class=\"\">apriori pr und marketing&nbsp;<\/h2> <p  class=\"lead\">Wir sind ein internationales, global t\u00e4tiges Team aus Pressesprechern, Marketingmanagern, Kundenberatern, Strategen, Kreativen, Grafik-Designern, Medienexperten, Journalisten, Kommunikationswissenschaftlern, Content- und Storytelling-Experten, Social Media Managern, Fotografen und Filmproduzenten.<\/p><\/div> <\/div> <div  class=\"row text-center\"> <div  class=\"col-xs-12\" data-editable=\"true\" data-content-shortcode=\"mesmerize_gallery id=&quot;mesmerize-gallery-1&quot; columns=&quot;4&quot; ids=&quot;16512,16510,16516,16482,14452,10851,5860,16526,16524,16522,16520,5414,5393,16528&quot; lb=&quot;1&quot; masonry=&quot;1&quot; size=&quot;medium&quot; link=&quot;file&quot; \"><div id='mesmerize-gallery-1' class='gallery-wrapper'><style type=\"text\/css\">\n                    @media only screen and (min-width: 768px) {\n                    [data-unique-id='mesmerize-gallery-1-6a57e39529e91'] dl {\n                        float: left;\n                        width: 25% !important;\n                        max-width:  25% !important;\n                        min-width:  25% !important;\n                    }\n\n                    [data-unique-id='mesmerize-gallery-1-6a57e39529e91'] dl:nth-of-type(4n +1 ) {\n                      clear: both;\n                      }\n                    }\n                <\/style><div id='mesmerize-gallery-1' class='mesmerize-gallery-1-dls-wrapper gallery-items-wrapper materialis-gallery' data-unique-id='mesmerize-gallery-1-6a57e39529e91'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-scaled.jpg'><img  width=\"450\" height=\"600\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-450x600.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-scaled.jpg 1920w\" data-sizes=\"(max-width: 450px) 100vw, 450px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/600;\" \/><noscript><img  width=\"450\" height=\"600\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-450x600.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7893-scaled.jpg 1920w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-scaled.jpg'><img  width=\"450\" height=\"600\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-450x600.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-scaled.jpg 1920w\" data-sizes=\"(max-width: 450px) 100vw, 450px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/600;\" \/><noscript><img  width=\"450\" height=\"600\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-450x600.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/20230621_175752-scaled.jpg 1920w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1.jpg'><img  width=\"600\" height=\"360\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-600x360.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-600x360.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1024x614.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-768x460.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1536x921.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-2048x1228.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1802x1080.jpg 1802w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1320x791.jpg 1320w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/360;\" \/><noscript><img  width=\"600\" height=\"360\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-600x360.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-600x360.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1024x614.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-768x460.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1536x921.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-2048x1228.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1802x1080.jpg 1802w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/cropped-IMG_7874-scaled-1-1320x791.jpg 1320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1.jpg'><img  width=\"600\" height=\"513\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-600x513.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-600x513.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1024x875.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-768x656.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1536x1313.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1264x1080.jpg 1264w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1320x1128.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1.jpg 2048w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/513;\" \/><noscript><img  width=\"600\" height=\"513\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-600x513.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-600x513.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1024x875.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-768x656.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1536x1313.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1264x1080.jpg 1264w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1-1320x1128.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/06\/Kopie-von-SF_Shooting-12-1.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s.jpg'><img  width=\"600\" height=\"335\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-600x335.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"aprioripr-Team-mobile\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-600x335.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-768x429.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s.jpg 926w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/335;\" \/><noscript><img  width=\"600\" height=\"335\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-600x335.jpg\"  class='mesmerize-gallery-1-image' alt=\"aprioripr-Team-mobile\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-600x335.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s-768x429.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/118913809_s.jpg 926w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824.jpg'><img  width=\"600\" height=\"400\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-600x400.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-1024x683.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-1620x1080.jpg 1620w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><noscript><img  width=\"600\" height=\"400\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-600x400.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-1024x683.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2019\/03\/cropped-camera-dslr-camera-equipment-1615824-1620x1080.jpg 1620w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD.jpg'><img  width=\"600\" height=\"400\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-600x400.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-1024x683.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD.jpg 1800w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/400;\" \/><noscript><img  width=\"600\" height=\"400\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-600x400.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD-1024x683.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/11\/Bild_5_Sponsoren-Feedback-PYD.jpg 1800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-scaled.jpg'><img  width=\"600\" height=\"450\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-600x450.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1320x990.jpg 1320w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/450;\" \/><noscript><img  width=\"600\" height=\"450\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-600x450.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_6736-1320x990.jpg 1320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-scaled.jpg'><img  width=\"450\" height=\"600\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-450x600.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-scaled.jpg 1920w\" data-sizes=\"(max-width: 450px) 100vw, 450px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/600;\" \/><noscript><img  width=\"450\" height=\"600\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-450x600.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-450x600.jpg 450w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-768x1024.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-600x800.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1152x1536.jpg 1152w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1536x2048.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1024x1365.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-810x1080.jpg 810w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-1320x1760.jpg 1320w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8681-scaled.jpg 1920w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-scaled.jpg'><img  width=\"600\" height=\"450\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-600x450.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1320x990.jpg 1320w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/450;\" \/><noscript><img  width=\"600\" height=\"450\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-600x450.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_8537-1320x990.jpg 1320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-scaled.jpg'><img  width=\"600\" height=\"450\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-600x450.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1320x990.jpg 1320w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/450;\" \/><noscript><img  width=\"600\" height=\"450\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-600x450.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7946-1320x990.jpg 1320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch.jpg'><img  width=\"300\" height=\"225\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-300x225.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-300x225.jpg 300w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch.jpg 640w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/><noscript><img  width=\"300\" height=\"225\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-300x225.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-300x225.jpg 300w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/Foto-3-Glastro\u0308sch.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen.jpg'><img  width=\"300\" height=\"200\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-300x200.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-300x200.jpg 300w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen.jpg 960w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><noscript><img  width=\"300\" height=\"200\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-300x200.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-300x200.jpg 300w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-768x512.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen-600x400.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2018\/09\/aprioripr-Team-Design-Offices-Muenchen.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-fancybox=\"mesmerize-gallery-1-group\" href='https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-scaled.jpg'><img  width=\"600\" height=\"450\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-600x450.jpg\"  class='mesmerize-gallery-1-image lazyload' alt=\"\" loading=\"lazy\" data-srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1320x990.jpg 1320w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/450;\" \/><noscript><img  width=\"600\" height=\"450\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-600x450.jpg\"  class='mesmerize-gallery-1-image' alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-600x450.jpg 600w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1024x768.jpg 1024w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-768x576.jpg 768w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1536x1152.jpg 1536w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-2048x1536.jpg 2048w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1440x1080.jpg 1440w, https:\/\/www.aprioripr.com\/wp-content\/uploads\/2023\/07\/IMG_7628-2-1320x990.jpg 1320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/noscript><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t\n\t\t<\/div>\n<script>(function($){window.MaterialisCaptionsGallery && window.MaterialisCaptionsGallery($('[data-unique-id=\"mesmerize-gallery-1-6a57e39529e91\"]'))})(jQuery)<\/script><\/div><\/div><\/div> <\/div><\/div><div  data-label=\"Content\" data-id=\"content--1\" data-export-id=\"content-12\" data-category=\"content\" class=\"content-12 content-section content-section-spacing content-relative\" id=\"content-1\" style=\"background-color: rgb(255, 255, 255); background-image: none;\"><div  class=\"section-separator-top\">\n    <svg  xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\" data-separator-name=\"triangle-negative\" class=\"section-separator-top\">\n\t<path  class=\"svg-white-bg\" d=\"M500.2,94.7L0,0v100h1000V0L500.2,94.7z\"><\/path>\n<\/svg>\n<\/div><div  class=\"gridContainer\"> <div  class=\"row text-center\"><div  class=\"section-title-col\" data-type=\"column\">  <p  class=\"lead\" style=\"text-align: left;\"><span  style=\"font-weight: 700;\">Clarity \u2013 Klarheit \u2013 Transparenz.<\/span><br >\nWir entwickeln Kernbotschaften , die durch stringentes Design unterst\u00fctzt werden und f\u00fchren damit Marken mit strukturierter Klarheit zum Erfolg. Wir kommunizieren f\u00fcr Ihre Marke glaubw\u00fcrdig und transparent.<br >\n<span  style=\"font-weight: 700;\">B-to-C und B-to-B Kommunikation.<\/span><br >\nSie k\u00f6nnen sowohl im Bereich der B-to-C als auch B-to-B Kommunikation auf uns vertrauen. Durch unsere jahrelange nationale und internationale multidisziplin\u00e4re Erfahrung optimieren wir Ihre Performance, Ihre Marke und Ihr Image.<\/p><img  alt=\"\" title=\"cropped-84413131_s.jpg\" data-src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-84413131_s.jpg\" class=\"custom-image lazyloaded\" src=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-84413131_s.jpg\"><\/div> <\/div> <div  class=\"row center-xs middle-xs\"> <div  class=\"col-sm-9\" data-type=\"column\"> <\/div> <\/div><\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>International und Multikulturell. Wir sind international t\u00e4tig und ein multikulturelles Team, das weltweit Unternehmen und Startups kreativ und performance-orientiert multilingual unterst\u00fctzt. Unsere PR- und Marketingexperten beraten Kunden u.a. in Australien, USA, in den Vereinigten Arabischen Emiraten, Italien, Polen, England, Frankreich, Deutschland, \u00d6sterreich und der Schweiz. Das apriori Team verf\u00fcgt \u00fcber fundierte Kenntnisse in der Leadgenerierung,&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pro\/page-templates\/full-width-page.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v14.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00dcber Uns | apriori pr und marketing<\/title>\n<meta name=\"description\" content=\"Wir sind eine international t\u00e4tige PR- und Marketing Agentur, die weltweit Unternehmen und Startups kreativ, performance-orientiert, multilingual unterst\u00fctzt. Unsere PR- und Marketingexperten beraten global t\u00e4tige innovative Unternehmen.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber Uns | apriori pr und marketing\" \/>\n<meta property=\"og:description\" content=\"Wir sind eine international t\u00e4tige PR- und Marketing Agentur, die weltweit Unternehmen und Startups kreativ, performance-orientiert, multilingual unterst\u00fctzt. Unsere PR- und Marketingexperten beraten global t\u00e4tige innovative Unternehmen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\" \/>\n<meta property=\"og:site_name\" content=\"apriori pr und marketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aprioriinternational\/?ref=bookmarks\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pg\/aprioriinternational\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T10:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-103998623_s.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/aprioripr\" \/>\n<meta name=\"twitter:site\" content=\"@aprioripr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/#organization\",\"name\":\"apriori pr und marketing\",\"url\":\"https:\/\/www.aprioripr.com\/de\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/aprioriinternational\/?ref=bookmarks\",\"https:\/\/www.instagram.com\/aprioripr\/?hl=de\",\"https:\/\/www.linkedin.com\/company\/10530298\/\",\"https:\/\/www.youtube.com\/channel\/UCzVZCt51PkhspqwzoBd7dYg\/featured?view_as=subscriber\",\"https:\/\/twitter.com\/aprioripr\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/#logo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2015\/06\/cropped-cropped-cropped-apriori-pr_and_marketing-Logo-1-1.png\",\"width\":1024,\"height\":1024,\"caption\":\"apriori pr und marketing\"},\"image\":{\"@id\":\"https:\/\/www.aprioripr.com\/de\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/#website\",\"url\":\"https:\/\/www.aprioripr.com\/de\/\",\"name\":\"apriori pr und marketing\",\"description\":\"International Public Relations and Marketing aprioripr\",\"publisher\":{\"@id\":\"https:\/\/www.aprioripr.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.aprioripr.com\/de\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.aprioripr.com\/wp-content\/uploads\/2020\/08\/cropped-103998623_s.jpg\",\"width\":848,\"height\":509},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/#webpage\",\"url\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\",\"name\":\"\\u00dcber Uns | apriori pr und marketing\",\"isPartOf\":{\"@id\":\"https:\/\/www.aprioripr.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/#primaryimage\"},\"datePublished\":\"2020-08-21T08:45:42+00:00\",\"dateModified\":\"2023-07-19T10:43:39+00:00\",\"description\":\"Wir sind eine international t\\u00e4tige PR- und Marketing Agentur, die weltweit Unternehmen und Startups kreativ, performance-orientiert, multilingual unterst\\u00fctzt. Unsere PR- und Marketingexperten beraten global t\\u00e4tige innovative Unternehmen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/\",\"url\":\"https:\/\/www.aprioripr.com\/de\/\",\"name\":\"About\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\",\"url\":\"https:\/\/www.aprioripr.com\/de\/internationale-pr-und-marketingagentur\/\",\"name\":\"\\u00dcber Uns\"}}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/pages\/14446"}],"collection":[{"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/comments?post=14446"}],"version-history":[{"count":13,"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/pages\/14446\/revisions"}],"predecessor-version":[{"id":16540,"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/pages\/14446\/revisions\/16540"}],"wp:attachment":[{"href":"https:\/\/www.aprioripr.com\/de\/wp-json\/wp\/v2\/media?parent=14446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}